{"id":2009,"date":"2021-11-30T02:00:40","date_gmt":"2021-11-30T01:00:40","guid":{"rendered":"https:\/\/monblogeur.tech\/index.php\/2021\/11\/30\/nantes-la-mise-au-point-de-kombouare-sur-ses-critiques-contre-les-jeunes-du-centre-de-formation-bfmtv-com\/"},"modified":"2021-11-30T02:00:40","modified_gmt":"2021-11-30T01:00:40","slug":"nantes-la-mise-au-point-de-kombouare-sur-ses-critiques-contre-les-jeunes-du-centre-de-formation-bfmtv-com","status":"publish","type":"post","link":"https:\/\/monblogeur.tech\/index.php\/2021\/11\/30\/nantes-la-mise-au-point-de-kombouare-sur-ses-critiques-contre-les-jeunes-du-centre-de-formation-bfmtv-com\/","title":{"rendered":"Nantes: la mise au point de Kombouar\u00e9 sur ses critiques contre les jeunes du centre de formation &#8211; BFMTV.COM"},"content":{"rendered":"<div class=\"cfbc967f0983488262956e73eca9483a\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3859091246952232\" crossorigin=\"anonymous\"><\/script>\r\n<!-- blok -->\r\n<ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-3859091246952232\" data-ad-slot=\"1334354390\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\n<\/div>\n<p>\u00ab\u00a0Je n\u2019ai qu\u2019une id\u00e9e en t\u00eate : faire monter les jeunes.\u00a0\u00bb <a href=\"\/football\/ligue-1\/nantes-il-ne-travaillait-pas-comment-kombouare-a-relance-lafont_AV-202111290310.html\" title=\"Nantes: &quot;Il ne travaillait pas&quot;, comment Kombouar\u00e9 a relanc\u00e9 Lafont\">Antoine Kombouar\u00e9<\/a> a tenu \u00e0 revenir sur ses propos <a href=\"\/football\/ligue-1\/nantes-kombouare-trouve-inquietant-le-niveau-des-jeunes-du-centre-de-formation_AV-202111050276.html\" title=\"Nantes: Kombouar\u00e9 trouve &quot;inqui\u00e9tant&quot; le niveau des jeunes du centre de formation\">pol\u00e9miques apr\u00e8s ses critiques tr\u00e8s comment\u00e9es \u00e0 l\u2019\u00e9gard des pensionnaires du centre de formation du FC Nantes<\/a> avant le match face \u00e0 Strasbourg (2-2). \u00ab\u00a0Ils sont loin du haut niveau\u00a0\u00bb, avait souffl\u00e9 l\u2019entra\u00eeneur nantais provoquant une onde de choc et <a href=\"\/football\/ligue-1\/nantes-pourquoi-le-fosse-se-creuse-entre-kombouare-et-les-formateurs_AV-202111100467.html\" title=\"Nantes: pourquoi le foss\u00e9 se creuse entre Kombouar\u00e9 et les formateurs\">quelques crispations chez les formateurs de la Joneli\u00e8re<\/a>. Ce lundi, c\u2019\u00e9tait donc un Kombouar\u00e9 en mode r\u00e9trop\u00e9dalage qui s\u2019est pr\u00e9sent\u00e9 face aux journalistes.<br \/>\u00ab\u00a0C\u2019est vous qui avez parl\u00e9 de pol\u00e9mique, il n\u2019y a jamais eu de pol\u00e9mique, a jug\u00e9 le Kanak. \u00c7a n\u2019a jamais \u00e9t\u00e9 une critique. Dans ces cas-l\u00e0, on ne parle jamais de formation. C\u2019est un constat, les jeunes qui sont l\u00e0 sont en retrait par rapport aux pros. C\u2019est normal. Moi aussi j\u2019ai \u00e9t\u00e9 jeune. Ici en plus (\u00e0 Nantes). Deschamps, Desailly ou moi, quand on est mont\u00e9 chez les pros, on n\u2019a pas \u00e9t\u00e9 des champions tout de suite. Les entra\u00eeneurs \u00e9taient patients. Aujourd\u2019hui ils (les jeunes) sont avec nous. Quand il y a des absents, ils ont du temps de jeu. Et quand ils sont bons, ils entrent dans la concurrence. S\u2019il y a des jeunes de qualit\u00e9, ils joueront.\u00a0\u00bb Et Kombouar\u00e9 ne demande que \u00e7a.<br \/><a href=\"\/football\/ligue-1\/ballon-d-or-le-7e-sacre-pour-messi-le-plus-conteste_AV-202111290554.html\" title=\"Ballon d\u2019or: le 7e sacre pour Messi, le plus contest\u00e9\">Ballon d\u2019or: le 7e sacre pour Messi, le plus contest\u00e9<\/a><\/p>\n<p>&copy; Copyright 2006-2020 BFMTV.com. Tous droits r\u00e9serv\u00e9s. Site \u00e9dit\u00e9 par NextInteractive<\/p>\n<p><a href=\"https:\/\/rmcsport.bfmtv.com\/football\/ligue-1\/nantes-la-mise-au-point-de-kombouare-sur-ses-critiques-contre-les-jeunes-du-centre-de-formation_AV-202111290351.html\">source<\/a><\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Je n\u2019ai qu\u2019une id\u00e9e en t\u00eate : faire monter les jeunes.\u00a0\u00bb Antoine Kombouar\u00e9 a tenu \u00e0 revenir sur ses propos pol\u00e9miques apr\u00e8s ses critiques tr\u00e8s comment\u00e9es \u00e0 l\u2019\u00e9gard des pensionnaires du centre de formation du FC Nantes avant le match face \u00e0 Strasbourg (2-2). \u00ab\u00a0Ils sont loin du haut niveau\u00a0\u00bb, avait souffl\u00e9 l\u2019entra\u00eeneur nantais provoquant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow1sXXCw:productID":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-2009","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/posts\/2009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/comments?post=2009"}],"version-history":[{"count":0,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/posts\/2009\/revisions"}],"wp:attachment":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/media?parent=2009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/categories?post=2009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/tags?post=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}