{"id":3128,"date":"2022-01-30T14:01:44","date_gmt":"2022-01-30T13:01:44","guid":{"rendered":"https:\/\/monblogeur.tech\/index.php\/2022\/01\/30\/le-numerique-et-la-formation-pour-relocaliser-une-partie-de-lachat-public-gazette-des-communes\/"},"modified":"2022-01-30T14:01:44","modified_gmt":"2022-01-30T13:01:44","slug":"le-numerique-et-la-formation-pour-relocaliser-une-partie-de-lachat-public-gazette-des-communes","status":"publish","type":"post","link":"https:\/\/monblogeur.tech\/index.php\/2022\/01\/30\/le-numerique-et-la-formation-pour-relocaliser-une-partie-de-lachat-public-gazette-des-communes\/","title":{"rendered":"Le num\u00e9rique et la formation pour &quot;relocaliser&quot; une partie de l&#039;achat public &#8211; Gazette des communes"},"content":{"rendered":"<div class=\"cfbc967f0983488262956e73eca9483a\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3859091246952232\" crossorigin=\"anonymous\"><\/script>\r\n<!-- blok -->\r\n<ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-3859091246952232\" data-ad-slot=\"1334354390\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\n<\/div>\n<p>D\u00e9j\u00e0 inscrit(e) ?<br \/>Identifiant et\/ou mot de passe non valides<br \/>Nous n\u2019avons pas reconnu votre email, veuillez indiquer un email valide, utilis\u00e9 lors de la cr\u00e9ation de votre compte.<br \/>Un message avec vos codes d&rsquo;acc\u00e8s vous a \u00e9t\u00e9 envoy\u00e9 par mail.<br \/>Pas encore inscrit(e) ?<br \/>Inscrivez-vous pour acc\u00e9der aux services de LaGazette.fr et \u00e0 la gestion de vos Newsletters et Alertes.<br \/>Mon compte Gazette<br \/>Menu<br \/>D\u00e9j\u00e0 inscrit(e) ?<br \/>Identifiant et\/ou mot de passe non valides<br \/>Nous n\u2019avons pas reconnu votre email, veuillez indiquer un email valide, utilis\u00e9 lors de la cr\u00e9ation de votre compte.<br \/>Un message avec vos codes d&rsquo;acc\u00e8s vous a \u00e9t\u00e9 envoy\u00e9 par mail.<br \/>Pas encore inscrit(e) ?<br \/>Inscrivez-vous pour acc\u00e9der aux services de LaGazette.fr et \u00e0 la gestion de vos Newsletters et Alertes.<br \/>Mon compte Gazette<br \/>Commande publique<br \/> \t\t\t<span class=\"articlePublication__data\"> \t\t\t\t\t\t\t\tPubli\u00e9 le 26\/01\/2022\t\t\t\t\t\t\t<\/span> \t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<span class=\"articlePublication__author\">\u2022  Par \t\t\t\t\t\t\t\t\t\t\t<a class=\"articlePublication__link\" href=\"https:\/\/www.lagazettedescommunes.com\/journaliste\/christine-berkovicius\/\" target=\"_blank\" rel=\"noopener\">Christine Berkovicius<\/a> \t\t\t\t\t \t\t\t\t\t\t\t\t<\/span> \t\t\t<span class=\"articlePublication__data\">\u2022  dans : \t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lagazettedescommunes.com\/rubriques\/france\/\" title=\"View all posts in France\" rel=\"category\" class=\"articlePublication__link\">France<\/a>\t\t\t\t\t\t\t<\/span> \t\t\t\t\t<br \/><i class=\"icon-alerte\"><\/i>Ma Gazette<br \/>S\u00e9lectionnez vos th\u00e8mes et cr\u00e9ez votre newsletter personnalis\u00e9e<br \/>Sur l\u2019Ile de La R\u00e9union, la commande publique, avec 1,9 milliards d\u2019euros de d\u00e9penses\u00a0 (10% du PIB local), est un instrument puissant pour doper l\u2019\u00e9conomie du territoire. Mais comme ailleurs, elle \u00e9chappe en partie aux entreprises de la r\u00e9gion. Pour plus d\u2019efficacit\u00e9, le Haut conseil de la commande publique de la R\u00e9union (HCCP), une instance r\u00e9activ\u00e9e il y a un peu plus de deux ans qui f\u00e9d\u00e8re 450 acteurs locaux, a d\u00e9cid\u00e9 de lancer un plan d\u2019action pour minimiser ces fuites vers l\u2019ext\u00e9rieur.<br \/>Il entend \u00ab\u00a0relocaliser\u00a0\u00bb 20% du total des achats, soit 380 millions d\u2019euros environ. Et pour y parvenir, il pr\u00e9conise une approche \u00ab\u00a0vertueuse\u00a0\u00bb du localisme, sans enfreindre les r\u00e8gles de la commande publique qui interdisent la pr\u00e9f\u00e9rence locale. \u00ab\u00a0Nous tentons d\u2019avoir un alignement entre intention &#8230;<br \/> \t\t\t\t\t\t\t\t\t[80% reste \u00e0 lire] \t\t\t\t\t\t\t<br \/>Article r\u00e9serv\u00e9 aux abonn\u00e9s<br \/>Gazette des Communes<br \/>VOUS N&rsquo;\u00eaTES PAS ABONN\u00e9 ?<br \/>D\u00e9couvrez nos formules et acc\u00e9dez aux articles en illimit\u00e9<br \/>Th\u00e8mes abord\u00e9s<br \/>Sur le m\u00eame sujet<br \/>D\u00e9serts m\u00e9dicaux, comment s&rsquo;en sortir ?<br \/>Cadres banque de France \u2013 mars 2022<br \/><span>Pr\u00e9parer ce concours<\/span> <i class=\"icon-chevron-right\"><\/i><br \/>Pharmacien inspecteur de sant\u00e9 publique \u2013 avril 2022<br \/><span>Pr\u00e9parer ce concours<\/span> <i class=\"icon-chevron-right\"><\/i><br \/>Personnel de sant\u00e9 param\u00e9dical dans les sp\u00e9cialit\u00e9s \u00ab Pu\u00e9ricultrice \u00bb et \u00ab Infirmier \u00bb &#8211; Occitanie avril 2022<br \/><span>Pr\u00e9parer ce concours<\/span> <i class=\"icon-chevron-right\"><\/i><br \/><i class=\"icon-geoloc\"><\/i> Nantes<br \/>2&egrave;mes Assises des &eacute;nergies renouvelables citoyennes<br \/><span>Information &amp; inscription<\/span> <i class=\"icon-chevron-right\"><\/i><br \/><i class=\"icon-geoloc\"><\/i> Paris<br \/>Les Prix Territoriaux &#8211; 22e &eacute;dition<br \/><span>Information &amp; inscription<\/span> <i class=\"icon-chevron-right\"><\/i><br \/><i class=\"icon-geoloc\"><\/i> 100% Digital<br \/>CLUB FINANCES n&deg;3<br \/><span>Information &amp; inscription<\/span> <i class=\"icon-chevron-right\"><\/i><br \/> \t\t\t\t\t\t\tLoi Climat et r&eacute;silience : d&eacute;crypter les impacts pour les collectivit&eacute;s territoriales\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"formation__days\">(1 jours)<\/span> \t\t\t\t\t\t\t\t\t\t\t\t\t<br \/><span>Information &amp; inscription<\/span> <i class=\"icon-chevron-right\"><\/i><br \/> \t\t\t\t\t\t\tParcours m&eacute;tier acheteur public\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"formation__days\">(4 jours)<\/span> \t\t\t\t\t\t\t\t\t\t\t\t\t<br \/><span>Information &amp; inscription<\/span> <i class=\"icon-chevron-right\"><\/i><br \/> \t\t\t\t\t\t\tOrganiser les &eacute;lections professionnelles (CAP, CCP et CST)\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"formation__days\">(1 jours)<\/span> \t\t\t\t\t\t\t\t\t\t\t\t\t<br \/><span>Information &amp; inscription<\/span> <i class=\"icon-chevron-right\"><\/i><br \/>Commentaires<\/p>\n<p> \t\t\t\t \t\t\t\t<small>Votre e-mail ne sera pas publi\u00e9<\/small> \t\t\t<\/p>\n<p> \t\t<\/p>\n<div id=\"recaptcha\"><\/div>\n<p>L\u2019hebdomadaire<br \/>N\u00b0 2599 &#8211; 24\/01\/2022<br \/> \t\t\t\t\t\t<a href=\"https:\/\/archives.lagazettedescommunes.com\/media\/FICHIER\/2022\/01\/24\/FICHIER_20220124_39704118.pdf\" target=\"_blank\" class=\"footer__basicLink\" rel=\"noopener\">Sommaire<\/a> \t\t\t\t\t\t\u2022 \t\t\t\t\t\t<a href=\"https:\/\/archives.lagazettedescommunes.com\" class=\"footer__basicLink\">Archives<\/a> \t\t\t\t\t<br \/>Le suppl\u00e9ment<br \/>N\u00b0 2599 &#8211; 24\/01\/2022<br \/> \t\t\t\t\t\t<a href=\"https:\/\/archives.lagazettedescommunes.com\/Cahiers\/PDF\/2599\" target=\"_blank\" class=\"footer__basicLink\" data-gm-tracking-1=\"PDF-cahier-detache\" data-gm-tracking-2=\"clic\" data-gm-tracking-3=\"2599\" rel=\"noopener\">PDF<\/a> \t\t\t\t\t\t\u2022 \t\t\t\t\t\t<a href=\"https:\/\/archives.lagazettedescommunes.com\/archives\/Cahiers\/\" class=\"footer__basicLink\">Archives<\/a> \t\t\t\t\t<br \/>Toutes les offres \u00e0 votre disposition<br \/>et ses services num\u00e9riques !<br \/>La newsletter<br \/> \t\t\t\t\t<span>Quotidienne<\/span> \t\t\t\t<br \/>Le magazine en<br \/> \t\t\t\t\t<span>version num\u00e9rique<\/span> \t\t\t\t<br \/>Magazine feuilletable sur<br \/> \t\t\t\t\t<span>l&rsquo;appli mobile Gazette kiosk<\/span> \t\t\t\t<br \/>Suivez la Gazette<br \/>D\u00e9j\u00e0 inscrit(e) ?<br \/>Identifiant et\/ou mot de passe non valides<br \/>Nous n\u2019avons pas reconnu votre email, veuillez indiquer un email valide, utilis\u00e9 lors de la cr\u00e9ation de votre compte.<br \/>Un message avec vos codes d&rsquo;acc\u00e8s vous a \u00e9t\u00e9 envoy\u00e9 par mail.<br \/>Pas encore inscrit(e) ?<br \/>Inscrivez-vous pour acc\u00e9der aux services de LaGazette.fr et \u00e0 la gestion de vos Newsletters et Alertes.<br \/>Mon compte Gazette<\/p>\n<p><a href=\"https:\/\/www.lagazettedescommunes.com\/786777\/le-numerique-et-la-formation-pour-relocaliser-une-partie-de-lachat-public\/\">source<\/a><\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e9j\u00e0 inscrit(e) ?Identifiant et\/ou mot de passe non validesNous n\u2019avons pas reconnu votre email, veuillez indiquer un email valide, utilis\u00e9 lors de la cr\u00e9ation de votre compte.Un message avec vos codes d&rsquo;acc\u00e8s vous a \u00e9t\u00e9 envoy\u00e9 par mail.Pas encore inscrit(e) ?Inscrivez-vous pour acc\u00e9der aux services de LaGazette.fr et \u00e0 la gestion de vos Newsletters et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow1sXXCw:productID":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3128","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/posts\/3128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/comments?post=3128"}],"version-history":[{"count":0,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/posts\/3128\/revisions"}],"wp:attachment":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/media?parent=3128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/categories?post=3128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/tags?post=3128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}