{"id":4774,"date":"2022-03-12T16:11:30","date_gmt":"2022-03-12T15:11:30","guid":{"rendered":"https:\/\/monblogeur.tech\/index.php\/2022\/03\/12\/une-formation-privee-pour-pallier-le-manque-de-veterinaires-ruraux-web-agri\/"},"modified":"2022-03-12T16:11:30","modified_gmt":"2022-03-12T15:11:30","slug":"une-formation-privee-pour-pallier-le-manque-de-veterinaires-ruraux-web-agri","status":"publish","type":"post","link":"https:\/\/monblogeur.tech\/index.php\/2022\/03\/12\/une-formation-privee-pour-pallier-le-manque-de-veterinaires-ruraux-web-agri\/","title":{"rendered":"Une formation priv\u00e9e pour pallier le manque de v\u00e9t\u00e9rinaires ruraux &#8211; Web-agri"},"content":{"rendered":"<div class=\"cfbc967f0983488262956e73eca9483a\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3859091246952232\" crossorigin=\"anonymous\"><\/script>\r\n<!-- blok -->\r\n<ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-3859091246952232\" data-ad-slot=\"1334354390\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\n<\/div>\n<p>Tapez un ou plusieurs mots-cl\u00e9s&#8230;<br \/>          <span class=\"article-meta\">          Publi\u00e9 le 11\/03\/2022&nbsp;\u00e0&nbsp;16:01        <\/span>        <span class=\"article-meta\">4 minutes de lecture<\/span>          <span class=\"article-meta\">1 <i class=\"zmdi zmdi-comment\"><\/i><\/span>      <br \/>                Le sujet fait d&#xE9;bat sur les r&#xE9;seaux comme au sein de la profession. A la rentr&#xE9;e 2022, UniLaSalle ouvrira la premi&#xE8;re &#xE9;cole de formation v&#xE9;t&#xE9;rinaire priv&#xE9;e sur son campus de Rouen.              <\/p>\n<p>Si le recrutement sur Parcoursup est actuellement lanc&eacute; pour permettre &agrave; une centaine d&rsquo;&eacute;tudiants d&rsquo;int&eacute;grer la <strong>formation v&eacute;t&eacute;rinaire<\/strong> en septembre 2022, le sujet fait d&eacute;bat sur les r&eacute;seaux. En plus de la <strong>d&eacute;sertification des v&eacute;t&eacute;rinaires en zone rurale<\/strong>, l&rsquo;&eacute;cole met en avant un chiffre&nbsp;: en 2021, 54&nbsp;% des primo-inscrits &agrave; l&rsquo;ordre national des v&eacute;t&eacute;rinaires ont re&ccedil;u leur dipl&ocirc;me dans un autre &Eacute;tat membre de l&rsquo;Union Europ&eacute;enne.<br \/>Nicolas LSC, <strong>v&eacute;t&eacute;rinaire<\/strong> r&eacute;agit&nbsp;:&laquo;&nbsp;En tant que v&eacute;to, je trouve &ccedil;a super que l&rsquo;on forme plus de v&eacute;t&eacute;rinaires, si &ccedil;a peut &ecirc;tre des ruraux, c&rsquo;est encore mieux. Par contre, je ne suis pas tr&egrave;s favorable &agrave; des prix de scolarit&eacute; &agrave; plus de 10&nbsp;000&nbsp;&euro; l&rsquo;ann&eacute;e sur 6 ans&hellip; Je pense que les <strong>v&eacute;tos<\/strong> qui sortiront avec une dette de plus de 50&nbsp;000&nbsp;&euro; se tourneront plus vers de la canine beaucoup plus rentable que de la rurale&hellip;&nbsp;&raquo;. &laquo;&nbsp;Qui mettra 90&nbsp;000&nbsp;&euro; pour que son gosse aille faire des c&eacute;sariennes &agrave; 3h du matin dans le froid&nbsp;&raquo; rench&eacute;rit Davy Biancamaria, &eacute;galement v&eacute;t&eacute;rinaire.<br \/>En effet, la formation affiche des frais de scolarit&eacute; annuels de 13&nbsp;000&nbsp;&euro; pour les trois premi&egrave;res ann&eacute;es, puis de 17&nbsp;500&nbsp;&euro; pour les trois derni&egrave;res ann&eacute;es du cursus, soit un total de 91&nbsp;500&nbsp;&euro;.<br \/>Philippe Choquet, directeur du groupe <strong>UniLaSalle<\/strong>, insiste cependant sur le fait que l&rsquo;&eacute;tablissement demeure un organisme &agrave; but non lucratif&nbsp;: &laquo;&nbsp;Oui, la formation va co&ucirc;ter cher. Le taux d&rsquo;encadrement sera d&rsquo;un prof pour cinq &eacute;l&egrave;ves, imaginez le salaire d&rsquo;un v&eacute;t&eacute;rinaire-enseignant avec un bac plus dix&hellip; Forc&eacute;ment, le prix avoisinera celui d&rsquo;une &eacute;cole de commerce, mais en tant qu&rsquo;association &agrave; but non lucratif, on ne fait aucun b&eacute;n&eacute;fice sur la formation, et s&rsquo;il y en avait, ils seraient restitu&eacute;s sous forme de bourse, d&rsquo;investissement &eacute;quipement ou de recherche. Ce n&rsquo;est pas pour r&eacute;mun&eacute;rer un actionnaire.&nbsp;&raquo;<br \/>L&rsquo;&eacute;cole envisage notamment la cr&eacute;ation d&rsquo;un <strong>h&ocirc;pital v&eacute;t&eacute;rinaire<\/strong> &agrave; horizon 2025, &eacute;l&eacute;ment n&eacute;cessaire &agrave; l&rsquo;accr&eacute;ditation AEEEV. Les premi&egrave;res ann&eacute;es de formation &eacute;tant consacr&eacute;es &agrave; l&rsquo;animal sain, les travaux pratiques concernent avant tout le dernier cycle. Des partenariats avec des &eacute;tablissements de la r&eacute;gion de Rouen permettront d&rsquo;effectuer les dissections pour le d&eacute;but de la formation. &nbsp;<br \/>&nbsp;<br \/>Pour Micka&euml;l Lallemand, &eacute;galement v&eacute;t&eacute;rinaire, &laquo;&nbsp;c&rsquo;est une 5&egrave;me &eacute;cole publique qu&rsquo;il aurait fallu cr&eacute;er pour r&eacute;pondre &agrave; la <strong>p&eacute;nurie de v&eacute;tos<\/strong>, pas une pompe &agrave; fric qui va avoir bien du mal &agrave; &eacute;valuer objectivement ses clients&nbsp;&raquo;. Elo&iuml;se Jouve, &eacute;tudiante &agrave; l&rsquo;<strong>&eacute;cole nationale de v&eacute;t&eacute;rinaire<\/strong> va dans le m&ecirc;me sens&nbsp;: &laquo;&nbsp;Les ENV ne sont pas gratuites, &agrave; moins d&rsquo;&ecirc;tre boursiers, c&rsquo;est 2&nbsp;500&nbsp;&euro; l&rsquo;ann&eacute;e, mais le prix est d&eacute;risoire par rapport &agrave; UniLaSalle&nbsp;&raquo;.<br \/>D&rsquo;autres saluent l&rsquo;initiative&nbsp;: &laquo;&nbsp;Que fait l&rsquo;&Eacute;tat aujourd&rsquo;hui pour &eacute;viter que la moiti&eacute; des jeunes dipl&ocirc;m&eacute;s v&eacute;t&eacute;rinaires exer&ccedil;ant en France ne soient dipl&ocirc;m&eacute;s &agrave; l&rsquo;&eacute;tranger apr&egrave;s des &eacute;tudes tr&egrave;s co&ucirc;teuses&nbsp;? Que fait l&rsquo;&Eacute;tat quand mon voisin jeune &eacute;leveur en milieu rural ne trouve plus de <strong>v&eacute;to<\/strong> pour soigner son b&eacute;tail&nbsp;? On a besoin de <strong>v&eacute;tos en milieu rural<\/strong> et on critique ceux qui essaient de trouver des solutions, ceux qui connaissent tr&egrave;s bien le monde agricole&nbsp;&raquo;, pointe du doigt Sandrine Perronnet.<br \/>Pour L&eacute;na Guipac, &laquo;&nbsp;c&rsquo;est effectivement hors de prix mais &ccedil;a a le m&eacute;rite de permettre une vraie alternative &agrave; l&rsquo;acc&egrave;s classique mais inaccessible pour beaucoup de jeunes pourtant brillants aux quatre &eacute;coles nationales v&eacute;t&eacute;rinaires&nbsp;&raquo;. Alors qu&rsquo;Aur&eacute;lie rappelle que les &eacute;tudes &agrave; l&rsquo;&eacute;tranger co&ucirc;tent &eacute;galement tr&egrave;s cher&nbsp;: &laquo;&nbsp;pour le Portugal, c&rsquo;est environ 50&nbsp;000&nbsp;&euro;. L&agrave; &ccedil;a reste fran&ccedil;ais. A voir si les bourses sont possibles&nbsp;&raquo;.<\/p>\n<blockquote><p>On a fait le v&ecirc;lage juridique du projet, et on peut dire que le veau n&rsquo;&eacute;tait pas bien positionn&eacute;&nbsp;!<\/p><\/blockquote>\n<p>C&rsquo;est un projet de longue date qui s&rsquo;est d&eacute;nou&eacute; la semaine derni&egrave;re. La cr&eacute;ation d&rsquo;une <strong>&eacute;cole v&eacute;t&eacute;rinaire priv&eacute;e<\/strong> par UniLaSalle &eacute;tait dans les tuyaux depuis 2007. Pour Philippe Choquet, &laquo;&nbsp;l&rsquo;ouverture de ce dossier a &eacute;t&eacute; un combat, face &agrave; une forteresse du public et de la corporation v&eacute;t&eacute;rinaire. Entre aujourd&rsquo;hui et 2026, on va pouvoir enfin recruter des professeurs qui font de la recherche, et construire l&rsquo;h&ocirc;pital qui permettra la professionnalisation. Ceux qui &eacute;voquent la non-conformit&eacute; en oubliant de pr&eacute;ciser que le minist&egrave;re de l&rsquo;enseignement sup&eacute;rieur dit que rien ne s&rsquo;oppose &agrave; une ouverture en septembre 2022, sont un petit peu teint&eacute;s de mauvaise foi. C&rsquo;est normal que nous n&rsquo;ayons pas toutes les accr&eacute;ditations, car la formation n&rsquo;est pas encore lanc&eacute;e, mais nous savons ce que c&rsquo;est que de conf&eacute;rer un dipl&ocirc;me de grade master via notre &eacute;cole d&rsquo;ing&eacute;nieur.&nbsp;&raquo;<br \/>L&#x27;UE veut aider les agriculteurs sans sacrifier le &#xAB;&#xA0;verdissement&#xA0;&#xBB; des cultures<br \/>12 mars \u00b7 4 min de lecture<br \/>Prix de la paille, les mam&#x27;agris et l&#x27;engraissement &#xE0; l&#x27;herbe sur le podium<br \/>12 mars \u00b7 1 min de lecture<br \/>La France doit encore abattre des millions d&#x27;animaux<br \/>12 mars \u00b7 4 min de lecture<br \/>Un message \u00e0 nous transmettre ? Un sujet \u00e0 nous proposer ?<br \/>Restez inform&#xE9;s en vous inscrivant &#xE0; notre newsletter<br \/>Flamb&#xE9;e du p&#xE9;trole et rupture d&#x2019;approvisionnement menacent la saison agricole<br \/>Palmar&#xE8;s, photos et replays des concours bovins<br \/>Le bl&#xE9; franchit les 400&#xA0;&#x20AC;\/t&#xA0;!<br \/>Le conflit en Ukraine fait flamber les prix des engrais<br \/>Les tracteurs jusqu&#x27;&#xE0; 500&#xA0;ch vont tout retourner avec la charrue Servo&#xA0;T 6000<br \/>La guerre en Ukraine &#xAB;&#xA0;ne sera pas sans cons&#xE9;quence&#xA0;&#xBB; sur le monde agricole<br \/>L&#x27;Europe doit &#xAB;&#xA0;produire plus&#xA0;&#xBB; pour &#xAB;&#xA0;&#xE9;viter une crise alimentaire mondiale&#xA0;&#xBB;<br \/>Emmanuel Macron a-t-il tenu ses promesses au monde agricole&#xA0;?<br \/>L&#x2019;agro&#xE9;cologie pl&#xE9;biscit&#xE9;e face &#xE0; un mod&#xE8;le conventionnel remis en cause<br \/>&#x2B; 49&#x20AC;\/t, &#x2B; 32&#xA0;&#x20AC;\/t, &#x2B;36&#xA0;&#x20AC;\/t: les cours du bl&#xE9;, ma&#xEF;s et colza explosent&#xA0;!<br \/>              &nbsp;&nbsp;&nbsp;Inscrivez-vous \u00e0 notre newsletter            <br \/>&copy; 2022 &#8211; Web-agri.fr &#8211; <a href=\"https:\/\/www.terre-net.fr\">Terre-net<\/a><\/p>\n<p><a href=\"https:\/\/www.web-agri.fr\/actualite-de-lelevage\/article\/206568\/ouverture-de-la-premiere-ecole-de-veterinaire-privee-en-2022\">source<\/a><\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Tapez un ou plusieurs mots-cl\u00e9s&#8230; Publi\u00e9 le 11\/03\/2022&nbsp;\u00e0&nbsp;16:01 4 minutes de lecture 1 Le sujet fait d&#xE9;bat sur les r&#xE9;seaux comme au sein de la profession. A la rentr&#xE9;e 2022, UniLaSalle ouvrira la premi&#xE8;re &#xE9;cole de formation v&#xE9;t&#xE9;rinaire priv&#xE9;e sur son campus de Rouen. Si le recrutement sur Parcoursup est actuellement lanc&eacute; pour permettre &agrave; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow1sXXCw:productID":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-4774","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/posts\/4774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/comments?post=4774"}],"version-history":[{"count":0,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/posts\/4774\/revisions"}],"wp:attachment":[{"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/media?parent=4774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/categories?post=4774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monblogeur.tech\/index.php\/wp-json\/wp\/v2\/tags?post=4774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}